{"id":1652,"date":"2023-07-21T14:08:13","date_gmt":"2023-07-21T12:08:13","guid":{"rendered":"https:\/\/www.giannicresci.com\/?p=1652"},"modified":"2026-05-08T09:21:25","modified_gmt":"2026-05-08T09:21:25","slug":"gli-speziali-fiorentini","status":"publish","type":"post","link":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/","title":{"rendered":"Gli Speziali Fiorentini"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1654 aligncenter\" src=\"http:\/\/www.giannicresci.com\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\" alt=\"Gli Speziali Fiorentini. Linea cosmetica creata da Gianni Cresci per Derbe di Firenze nel 1992\" width=\"800\" height=\"878\" srcset=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg 800w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4791-273x300.jpg 273w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4791-768x843.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gli Speziali Fiorentini<\/strong><\/p>\n<p>Arte delle sfere e dei mortai, delle odorose officine, degli aromi e delle Tinture, delle interrogazioni e trasformazioni, l\u2019Arte degli Speziali \u00e8 la sesta delle Arti Maggiori Fiorentine.<br \/>\nLa Corporazione, nata nella Firenze del \u2018300, ha segnato la storia della medicina e della profumeria: per i filosofi dell\u2019Arte la malattia non \u00e8 pi\u00f9 segno della punizione divina per colpe connesse, ma una turbata armonia che lo Speziale deve saper ricomporre. Sapere rigoroso del fine rimedio e del medicamento che ritroviamo nel <strong>Ricettario Fiorentino<\/strong> del 1400, considerato l\u2019operato di farmacopea pi\u00f9 antica e rigorosa che si conosca.<br \/>\nMa l\u2019arte degli Speziali \u00e8 anche l\u2019arte del segreto tramandato e pi\u00f9 spesso taciuto: si pensi che Francesco Redi, soprintendente alla spezieria di <strong>Cosimo dei Medici<\/strong>, custodiva gelosamente financo la ricetta della \u00ab<strong>cioccolata con l\u2019odore dei Gelsomini<\/strong>\u00bb tanto cara a Cosimo; alle pressanti richieste di colleghi e amici speziali che ne chiedevano i modi di preparazione to cara a Cosimo; alle pressanti richieste di colleghi e amici speziali che ne chiedevano i modi di preparazione era costretto a negarsi con modi gentili ma decisi:<br \/>\n\u00abSo che V.S. \u00e8 discreta, e che sa molto bene insino a dove si pu\u00f2 arrivare a parlare\u00bb.<br \/>\nL&#8217;interesse di Cosimo per \u00abl&#8217;odore gentilissimo del gelsomino, che mescolato colla cannella, colla vaniglia, coll&#8217;ambra e col muschio fa un sentire stupendo a coloro che del <strong>cioccolatte<\/strong> si dilettano\u00bb si era trasformato in una passione intensa, quasi smodata. Fu cos\u00ec il Granduca ad importare il fiore prediletto e a diffonderlo nei giardini rinascimentali; per questa ragione il <strong>Jasminum Sambac<\/strong>, la specie di gelsomino pi\u00f9 amata nei paesi arabi, \u00e8 nota in Italia col nome di \u201c<strong>Granduca di Toscana<\/strong>\u201d.<br \/>\nCustode geloso dell&#8217;arte della trasformazione e della creazione composta, lo Speziale \u00e8 comunque tentato dai desideri della ricerca. Prudente per esigenze di riservatezza, oscuro nell&#8217;eloquio secondo una ordinata strategia del segreto, non pu\u00f2 tuttavia astenersi dal comunicare. La ricerca \u00e8 solitaria ma \u00e8 anche parte di una grande opera; lo stesso Redi ha premiato talvolta la tentazione di condividere le preziose scoperte odorose:<br \/>\n\u00abAssaggi &#8211; scriveva al padre <strong>Tommaso Strozzi<\/strong> &#8211; un poco il polviglio del Tonc. [&#8230;] L&#8217;accompagno con alcuni altri saggi maggiori di iacinti, di vainiglie, di giunchiglie, di mughetti, di ambra, di muschi greci e di puro del Brasil.\u00bb<br \/>\nNon sempre per\u00f2 la condivisione del segreto \u00e8 frutto di vera scelta: succede che sia la storia degli eventi a determinarla. Cos\u00ec, quando nel 1533 Caterina de\u2019 Medici arriva a Parigi, e Firenze era ormai da un secolo il pi\u00f9 importante centro di produzione profumiera, parte del sapere dei sottili Speziali Fiorentini \u201cuffiziali da ornamento e da profumo\u201d viene svelato. Nasce cos\u00ec la prestigiosa tradizione profumiera francese: Renato Bianco, speziale profumiere che Caterina aveva portato con s\u00e9, diviene il famoso &#8220;<strong>Ren\u00e9 le Florentin<\/strong>&#8221; alla cui bottega parigina accorrono da ogni parte per acquistare le sue ricercate preparazione profumate.\u2028 D&#8217;altra parte le dame dell&#8217;epoca gi\u00e0 intuivano quali strumenti deliziosi per i giochi di seduzione l&#8217;arte degli speziali avrebbe potuto offrire. E <strong>Caterina<\/strong> aveva regalato alle donne francesi un altro elemento straordinario per la complessa strategia femminile: la biancheria intima. Prima dell&#8217;arrivo a Parigi della &#8220;piccola&#8221; Medici, infatti, le donne francesi sotto le gonne non portavano proprio niente. Le culottes, fino ad allora elemento esclusivo dell&#8217;abbigliamento maschile, e le miscele profumate degli speziali iniziano a comporsi in un rito intricato di negazioni e concessioni, di presenze aromatiche e di ricordi emozionati.\u2028Almeno per un secolo i francesi non vollero dimenticare l&#8217;origine fiorentina della scienza speziale dei profumi.<br \/>\nA <strong>Margherita d&#8217;Orleans<\/strong>, partita dalla Francia per Firenze perch\u00e9 promessa sposa del Granduca Cosimo III, la madre rimasta in terra francese doveva raccomandarsi: \u00abRicordati di mandarmi molti di quei preziosi profumi del Granduca\u00bb.\u2028Ma l&#8217;arte degli speziali profumieri fiorentini non ha trovato solo presso i francesi accoglienze entusiaste ed ammirate.<br \/>\nL\u2019\u201c<strong>Acqua de Regina<\/strong>\u201d preparata dagli speziali del convento di <strong>S. Maria Novella<\/strong> nel &#8216;300, dovr\u00e0 attendere il 1742 per guadagnarsi la piena notoriet\u00e0. Portata in Germania da J.P. Feminis di Val Vigezzo, a partire da quella data prende il nome di \u201cAcqua di Colonia\u201d, in onore della citt\u00e0 in cui viene prodotta. <em>Ancora esiste una missiva e un&#8217;opera che deve essere continuata.<\/em><\/p>\n<p>Gianni Cresci, Firenze, 1992<br \/>\n[Testo di presentazione della linea <a href=\"https:\/\/giannicresci.com\/Gianni-Cresci\/gli-speziali-fiorentini\/\"><em>Gli Speziali Fiorentini<\/em><\/a>, creata per Derbe di Firenze nel 1992]<\/p>\n<figure id=\"attachment_1657\" aria-describedby=\"caption-attachment-1657\" style=\"width: 800px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1657\" src=\"http:\/\/www.giannicresci.com\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4792.jpg\" alt=\"Gianni Cresci ha creato gli Speziali Fiorentini nel 1992 per Derbe di Firenze\" width=\"800\" height=\"1012\" srcset=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4792.jpg 800w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4792-237x300.jpg 237w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Speziali-Fiorentini-Gianni-Cresci-IMG_4792-768x972.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-1657\" class=\"wp-caption-text\">Gianni Cresci ha creato gli <a href=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/\"><strong>Speziali Fiorentini<\/strong><\/a> nel 1992 per Derbe di Firenze<\/figcaption><\/figure>\n<p><a id=\"cy-effective-orcid-url\" class=\"underline\" style=\"vertical-align: top;\" href=\"https:\/\/orcid.org\/0009-0001-8027-0056\" target=\"orcid.widget\" rel=\"me noopener noreferrer\"><br \/>\n<img decoding=\"async\" style=\"width: 1em; margin-inline-start: 0.5em;\" src=\"https:\/\/orcid.org\/sites\/default\/files\/images\/orcid_16x16.png\" alt=\"ORCID iD icon\" \/><br \/>\nhttps:\/\/orcid.org\/0009-0001-8027-0056<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Gli Speziali [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[33,38,71,82,97],"class_list":["post-1652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testi","tag-cosmesi","tag-erboristeria","tag-odori","tag-profumi","tag-speziali-fiorentini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli Speziali Fiorentini - Gianni Cresci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli Speziali Fiorentini - Gianni Cresci\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; Gli Speziali [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/\" \/>\n<meta property=\"og:site_name\" content=\"Gianni Cresci\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T12:08:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"878\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"headline\":\"Gli Speziali Fiorentini\",\"datePublished\":\"2023-07-21T12:08:13+00:00\",\"dateModified\":\"2026-05-08T09:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/\"},\"wordCount\":754,\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\",\"keywords\":[\"Cosmesi\",\"Erboristeria\",\"Odori\",\"Profumi\",\"Speziali Fiorentini\"],\"articleSection\":[\"Testi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/\",\"name\":\"Gli Speziali Fiorentini - Gianni Cresci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\",\"datePublished\":\"2023-07-21T12:08:13+00:00\",\"dateModified\":\"2026-05-08T09:21:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg\",\"width\":800,\"height\":878,\"caption\":\"Derbe. Speziali Fiorentini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2023\\\/07\\\/21\\\/gli-speziali-fiorentini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli Speziali Fiorentini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\",\"name\":\"Gianni Cresci\",\"description\":\"Semiotica, Musica, Design e Comunicazione.\",\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"width\":512,\"height\":512,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\"},\"sameAs\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\"],\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/author\\\/admin_gianni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli Speziali Fiorentini - Gianni Cresci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/","og_locale":"it_IT","og_type":"article","og_title":"Gli Speziali Fiorentini - Gianni Cresci","og_description":"&nbsp; &nbsp; Gli Speziali [&hellip;]","og_url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/","og_site_name":"Gianni Cresci","article_published_time":"2023-07-21T12:08:13+00:00","article_modified_time":"2026-05-08T09:21:25+00:00","og_image":[{"width":800,"height":878,"url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#article","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/"},"author":{"name":"admin","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"headline":"Gli Speziali Fiorentini","datePublished":"2023-07-21T12:08:13+00:00","dateModified":"2026-05-08T09:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/"},"wordCount":754,"publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg","keywords":["Cosmesi","Erboristeria","Odori","Profumi","Speziali Fiorentini"],"articleSection":["Testi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/","name":"Gli Speziali Fiorentini - Gianni Cresci","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#primaryimage"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg","datePublished":"2023-07-21T12:08:13+00:00","dateModified":"2026-05-08T09:21:25+00:00","breadcrumb":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#primaryimage","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2023\/07\/Derbe-Speziali-Fiorentini-Gianni-Cresci-IMG_4791.jpg","width":800,"height":878,"caption":"Derbe. Speziali Fiorentini"},{"@type":"BreadcrumbList","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2023\/07\/21\/gli-speziali-fiorentini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giannicresci.com\/Gianni-Cresci\/"},{"@type":"ListItem","position":2,"name":"Gli Speziali Fiorentini"}]},{"@type":"WebSite","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/","name":"Gianni Cresci","description":"Semiotica, Musica, Design e Comunicazione.","publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giannicresci.com\/Gianni-Cresci\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","width":512,"height":512,"caption":"admin"},"logo":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg"},"sameAs":["https:\/\/giannicresci.com\/Gianni-Cresci"],"url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/author\/admin_gianni\/"}]}},"_links":{"self":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":1,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":1733,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/1652\/revisions\/1733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media\/1659"}],"wp:attachment":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/tags?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}