{"id":168,"date":"2014-11-28T12:46:19","date_gmt":"2014-11-28T11:46:19","guid":{"rendered":"http:\/\/www.giannicresci.com\/?p=168"},"modified":"2014-11-28T12:46:19","modified_gmt":"2014-11-28T11:46:19","slug":"semiotica-della-musica-espressione-e-contenuto","status":"publish","type":"post","link":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/","title":{"rendered":"Semiotica della musica. Espressione e Contenuto"},"content":{"rendered":"<h4>Piano dell&#8217;espressione e piano del contenuto<\/h4>\n<p style=\"text-align: justify;\">Alla nota distinzione tra codice e codice-sistema di Umberto Eco, potremmo far corrispondere, con l&#8217;intento\u00a0di circoscrivere il campo e giustificare le scelte di metodo, due approcci allo studio della semiotica della musica che implicano differenti considerazioni sulla possibilit\u00e0 e sulle modalit\u00e0 della musica di significare &#8211; in quale modo la musica sia <em>segno<\/em> o, meglio, quali <em>modalit\u00e0 segniche<\/em> si ritrovino nel fenomeno musicale &#8211; cos\u00ec come sulle differenti pertinenze nell&#8217;analisi di un testo. Le analisi <em>neutre<\/em> si occupano dell&#8217;organizzazione autonoma di uno solo dei due piani, quello dell&#8217;espressione. Questa organizzazione autonoma \u00e8 appunto il codice sistema o s-codice. Il criterio di pertinenza adottato da questo tipo di analisi per individuare i tratti in cui pu\u00f2 essere scomposto il testo, non si appoggia sul piano del contenuto e sulle <em>funzioni d&#8217;uso<\/em> contratte dal testo stesso.\u00a0Le analisi che invece si occupano del s-codice sul piano del contenuto sono state fino ad oggi di competenza della psicologia e della sociologia teorica e non vengono qui prese in considerazione. Prima di occuparci delle definizioni del legame tra i due piani, vorremmo introdurre il concetto di <em>senso<\/em>, inteso qui come l&#8217;insieme di relazioni che una unit\u00e0 intrattiene con le altre unit\u00e0 all&#8217;interno di un sistema. Ne segue che il <em>senso in musica<\/em> si appoggia sulle funzioni sintattiche contratte dalle parti di una catena e si determina dallo <em>scarto<\/em> che pu\u00f2 verificarsi rispetto alla funzione che &#8216;prevedibilmente&#8217; la parte avrebbe dovuto contrarre. Questo tipo di relazione tra le parti sembra avere, con modalit\u00e0 e caratteristiche particolari, un certo <em>valore prognostico<\/em>. Se non possiamo, in effetti, dire che da un antecedente si inferisce il conseguente, poich\u00e9 non si riscontrano casi di vera e propria <em>rezione<\/em>, il linguaggio musicale mostra per\u00f2 di appoggiarsi ad un sistema di attese, culturalmente determinate, che si fondano sulla maggiore o minore probabilit\u00e0 che ad una certa parte della catena ne succeda una certa altra.<br \/>\nLe ricerche sui codici musicali mirano a definire la convenzione che collega il piano dell&#8217;espressione al piano del contenuto. Ci proponiamo di verificare la natura del legame che unisce i due piani ed in quali modi e secondo quali punti di vista il legame stesso esista. Ogni volta che cerchiamo nella musica una correlazione segnica, dizionariale o meno, i risultati sono comprensibilmente deludenti. Correlazioni di questo tipo tra i due piani in musica si riscontrano in un ristretto ventaglio di casi riconducibili all&#8217;uso della musica come <em>segnale<\/em>. Un modo per superare il problema potrebbe essere quello di considerare il significato in termini di interpretazione in senso <em>Peirciano<\/em>: valutare quindi la possibilit\u00e0 per la musica di essere <em>interpretabile<\/em> &#8211; ovvero la possibilit\u00e0 per un significante di essere tradotto con un altro significante, detto <em>l&#8217;interpretante<\/em> del primo, che \u201cne allarghi la comprensione\u201d (ECO, 1984, p.51) &#8211; la condizione sufficiente per parlare di significato musicale. In effetti la musica permette di sostituire un significante con un altro significante, come nel caso di una trasposizione di una melodia in un&#8217;altra\u00a0tonalit\u00e0 o la sua riproposizione con i parametri timbrici mutati. Tuttavia in entrambe le circostanze i rapporti intervallari restano immutati e riscontriamo quella <em>conformit\u00e0<\/em> che caratterizza, secondo la classificazione di Hjelmslev, i sistemi <em>monoplanari<\/em>. Questi sistemi \u201cpur essendo interpretabili come gli altri sistemi semiotici (&#8230;) sono caratterizzati dal fatto che (&#8230;) l&#8217;interpretazione semantica che ne sar\u00e0 data riprodurr\u00e0 le stesse articolazioni e potr\u00e0 essere rappresentata secondo le stesse regole della forma interpretata\u201d (GREIMAS, 1986, p.182)<br \/>\nLa difficolt\u00e0 di correlare un insieme di note al piano del contenuto compromette la possibilit\u00e0 di ritrovare i due <em>livelli di articolazione<\/em> nel sistema musicale. Infatti, mentre l&#8217;individuazione dei tratti distintivi che costituiscono la nota rivela una certa similarit\u00e0 tra lingua naturale e musica, non altrettanto possiamo dire riguardo alla prima articolazione a causa della difficolt\u00e0, come gi\u00e0 detto, di assegnare alle sequenze una funzione distintiva paragonabile a quella delle parole nella lingua. Ma anche al livello della seconda articolazione si riscontrano alcuni problemi specifici: quelli che sono noti come tratti distintivi della nota, ovvero l&#8217;altezza, l&#8217;intensit\u00e0, il timbro, la durata, se verificati a prescindere\u00a0dal\u00a0contesto, si comportano, ad eccezione dell&#8217;altezza, come delle varianti. Nel caso della lingua, per esempio, i fonemi T e D si distinguono per i tratti in cui sono scomponibili; se il fonema T si scompone nei tratti: dentale, occlusiva, non sonora, e il fonema D in: dentale, occlusiva, sonora, se ne deduce che i tratti distintivi siano: sonora e non sonora. Nel caso della musica, due note DO e RE, assolutamente decontestualizzate, hanno come tratto distintivo l&#8217;altezza, ma al mutare degli altri tratti le due note sembrano mantenere la loro identit\u00e0. Sarebbe il rapporto intervallare a definirle. Evidentemente la questione deve essere posta in altri termini: siccome le note contraggono una funzione all&#8217;interno di un contesto, dovremo di volta in volta pertinentizzare alcuni tratti invece di altri secondo il punto di vista adottato. Per esempio, un&#8217;analisi che miri ad individuare la sintassi melodica del repertorio dei corali di Bach, considerer\u00e0 pertinenti la durata, la posizione, il grado della nota e non pertinenti altri tratti come il timbro e l&#8217;intensit\u00e0. (cfr. BARONI &#8211; JACOBONI 1976) Nella presente nota e in quelle successive, si fa\u00a0riferimento al repertorio classico e conseguentemente \u00e8\u00a0considerato pertinente il tratto dell&#8217;altezza o, pi\u00f9 esattamente, il <em>rapporto intervallare<\/em>\u00a0che definisce la relazione tra accordi e tra le note di un accordo.<\/p>\n<p>[highlight]Tratto da Gianni Cresci e Luciano Menconi, <em>I cinque tratti della struttura fondamentale del linguaggio secondo\u00a0Hjelmslev. La verifica nel sistema musicale attraverso una prospettiva armonico-funzionale<\/em>, Universit\u00e0 di Bologna, 1988[\/highlight]<\/p>\n<p><b><strong>1.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-espressione-e-contenuto\/\">Piano dell&#8217;espressione e piano del contenuto<\/a><\/strong><br \/>\n<strong>2.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-processo-e-sistema\/\" target=\"_blank\">Processo e sistema<\/a><\/strong><br \/>\n<strong>3.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-la-prova-di-commutazione\/\">Prova di commutazione<\/a><\/strong><br \/>\n<strong>4.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-combinazione-e-rezione\/\">Combinazione e rezione<\/a><\/strong><br \/>\n<strong>5.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-non-conformita\/\">(Non) conformit\u00e0<\/a><\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">[hr]<\/p>\n<p style=\"text-align: justify;\">BARONI Mario &#8211; JACOBONI, Carlo<br \/>\n1976 Verso una grammatica della melodia, Bologna, Forni<\/p>\n<p style=\"text-align: justify;\">ECO, Umberto<br \/>\n1984 Semiotica e filosofia del linguaggio, Torino, Einaudi<\/p>\n<p style=\"text-align: justify;\">HJELMSLEV, Louis<br \/>\n1968 I fondamenti della teoria del linguaggio, Torino, Einaudi<br \/>\n1985 &#8220;La struttura fondamentale del linguaggio\u201d in Versus n.43<\/p>\n<p style=\"text-align: justify;\">GREIMAS, Algirdas Julien<br \/>\n1986 Semiotica &#8211; Dizionario ragionato della teoria del linguaggio, Firenze, La casa Uscher<\/p>\n<p style=\"text-align: justify;\">ZINNA, Alessandro<br \/>\n1985 Introduzione in\u00a0<em>Versus<\/em>\u00a0n.43<\/p>\n<p style=\"text-align: justify;\">[hr]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piano dell&#8217;espressione e piano [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[48,50,70,89,93,107],"class_list":["post-168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testi","tag-greimas","tag-hjelmslev","tag-musicologia","tag-semiotica","tag-semiotica-della-musica","tag-umberto-eco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semiotica della musica. Espressione e Contenuto - Gianni Cresci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semiotica della musica. Espressione e Contenuto - Gianni Cresci\" \/>\n<meta property=\"og:description\" content=\"Piano dell&#8217;espressione e piano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/\" \/>\n<meta property=\"og:site_name\" content=\"Gianni Cresci\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-28T11:46:19+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"headline\":\"Semiotica della musica. Espressione e Contenuto\",\"datePublished\":\"2014-11-28T11:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/\"},\"wordCount\":1023,\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/semiotica-dell-musica-espressione-contenuto.jpg\",\"keywords\":[\"Greimas\",\"Hjelmslev\",\"Musicologia\",\"Semiotica\",\"Semiotica della musica\",\"Umberto Eco\"],\"articleSection\":[\"Testi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/\",\"name\":\"Semiotica della musica. Espressione e Contenuto - Gianni Cresci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/semiotica-dell-musica-espressione-contenuto.jpg\",\"datePublished\":\"2014-11-28T11:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/semiotica-dell-musica-espressione-contenuto.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/semiotica-dell-musica-espressione-contenuto.jpg\",\"width\":302,\"height\":252,\"caption\":\"Semiotica della Musica - Espressione e Contenuto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/11\\\/28\\\/semiotica-della-musica-espressione-e-contenuto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semiotica della musica. Espressione e Contenuto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\",\"name\":\"Gianni Cresci\",\"description\":\"Semiotica, Musica, Design e Comunicazione.\",\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"width\":512,\"height\":512,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\"},\"sameAs\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\"],\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/author\\\/admin_gianni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semiotica della musica. Espressione e Contenuto - Gianni Cresci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/","og_locale":"it_IT","og_type":"article","og_title":"Semiotica della musica. Espressione e Contenuto - Gianni Cresci","og_description":"Piano dell&#8217;espressione e piano [&hellip;]","og_url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/","og_site_name":"Gianni Cresci","article_published_time":"2014-11-28T11:46:19+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#article","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/"},"author":{"name":"admin","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"headline":"Semiotica della musica. Espressione e Contenuto","datePublished":"2014-11-28T11:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/"},"wordCount":1023,"publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/semiotica-dell-musica-espressione-contenuto.jpg","keywords":["Greimas","Hjelmslev","Musicologia","Semiotica","Semiotica della musica","Umberto Eco"],"articleSection":["Testi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/","name":"Semiotica della musica. Espressione e Contenuto - Gianni Cresci","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#primaryimage"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/semiotica-dell-musica-espressione-contenuto.jpg","datePublished":"2014-11-28T11:46:19+00:00","breadcrumb":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#primaryimage","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/semiotica-dell-musica-espressione-contenuto.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/semiotica-dell-musica-espressione-contenuto.jpg","width":302,"height":252,"caption":"Semiotica della Musica - Espressione e Contenuto"},{"@type":"BreadcrumbList","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/11\/28\/semiotica-della-musica-espressione-e-contenuto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giannicresci.com\/Gianni-Cresci\/"},{"@type":"ListItem","position":2,"name":"Semiotica della musica. Espressione e Contenuto"}]},{"@type":"WebSite","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/","name":"Gianni Cresci","description":"Semiotica, Musica, Design e Comunicazione.","publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giannicresci.com\/Gianni-Cresci\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","width":512,"height":512,"caption":"admin"},"logo":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg"},"sameAs":["https:\/\/giannicresci.com\/Gianni-Cresci"],"url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/author\/admin_gianni\/"}]}},"_links":{"self":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":0,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media\/200"}],"wp:attachment":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media?parent=168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/categories?post=168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/tags?post=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}