{"id":476,"date":"2014-12-08T18:29:16","date_gmt":"2014-12-08T17:29:16","guid":{"rendered":"http:\/\/www.giannicresci.com\/?p=476"},"modified":"2014-12-08T18:29:16","modified_gmt":"2014-12-08T17:29:16","slug":"semiotica-della-musica-combinazione-e-rezione","status":"publish","type":"post","link":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/","title":{"rendered":"Semiotica della musica. Combinazione e rezione"},"content":{"rendered":"<h4>Combinazione e Rezione<\/h4>\n<p style=\"text-align: justify;\">Il quarto tratto fondamentale della struttura di base del linguaggio \u00e8 l&#8217;esistenza di relazioni ben definite tra unit\u00e0 linguistiche dette di combinazione e rezione. La <strong>combinazione<\/strong> \u00e8 una <strong>relazione tra due variabili<\/strong>, mentre la <strong>rezione<\/strong> lo \u00e8 tra <strong>una variante e una costante<\/strong> (in questo caso si dice <em>unilaterale<\/em>), o tra due costanti (in questo caso si dice <em>reciproca<\/em>). In musica, combinazione e rezione, in quanto relazioni tra parti della catena di cui si costituisce il processo, assumono un&#8217;importanza euristica fondamentale, superiore a quella che Hjelmslev sottolinea nei sistemi passe-partout rispetto agli altri quattro tratti. Abbiamo accennato negli altri capitoli come il <em>senso<\/em> in musica nasca dallo strutturarsi del materiale sonoro in un processo implicantesi parte dopo parte. Abbiamo cio\u00e8 visto come in musica si riscontri il trionfo di quella <em>prognostica<\/em> che fin dagli stoici era stata stabilita come un meccanismo fondamentale della semiosi. <strong>Il senso in musica nasce quindi non dall&#8217;equivalenza, dalla correlazione tra espressione e contenuto<\/strong> come avviene nei sistemi di segni<strong>, <\/strong>ma dalla<strong> inferenza, <\/strong>dalla relazione (combinazione e rezione) contratta dalle parti di una catena, dalla realizzazione o non realizzazione\u00a0di un certo evento prognosticato.<\/p>\n<p style=\"text-align: justify;\">Saranno quindi le relazioni di combinazione e rezione a permettere di spiegare e analizzare il senso di un brano. <strong>In musica non esiste vera e propria rezione<\/strong>; non esiste cio\u00e8 un caso evidente di funzione in cui la presenza di un funtivo \u00e8 condizione necessaria per la presenza dell&#8217;altro come invece succede nelle lingue naturali (per esempio in italiano tra la lettera q e la lettera u). Anche nei s-codici pi\u00f9 rigidi come quello <strong>seriale<\/strong>, \u00e8 vero che i dodici suoni compresi nell&#8217;ottava si succedono costantemente secondo l&#8217;ordine stabilito dalla serie, ma \u00e8 anche vero che ciascuno di essi al di fuori della serie, in armonia o nelle fasi di passaggio, pu\u00f2 comparire senza la necessit\u00e0 di essere preceduto o seguito dal suono adiacente nella serie. Tuttavia ogni <strong>s-codice musicale<\/strong> &#8211; e noi facciamo riferimento a quello <strong>armonico-tonale<\/strong> &#8211; si struttura su dipendenze se non in relazione di rezione rigorosa, sicuramente probabilistica. Sulla base di queste considerazioni, la musica, fin dagli anni &#8217;60, \u00e8 stata avvicinata dalla e alla <em>teoria dell&#8217;informazione<\/em>. La musica \u00e8 stata cos\u00ec studiata come un processo stocastico di Markov, cio\u00e8 un processo probabilistico in cui le probabilit\u00e0 dipendono dagli eventi precedenti nella catena, poi tradotto quantitativamente in termini di <em>ridondanza<\/em>, entropia, informazione, feedback.<br \/>\nPrima di spiegare in quali termini questi due campi cos\u00ec apparentemente lontani abbiano trovato punti di incontro, diamo una breve occhiata ad alcune relazioni che strutturano il sistema armonico-tonale. Al livello melodico esso si struttura su un centro tonale, la Tonica, che oltre a combinarsi con tutti gli altri gradi \u00e8 implicato necessariamente dal VII grado, ovvero la Sensibile. Al livello armonico l&#8217;accordo sul V grado, con la funzione di Dominante, risolve su quello di Tonica costituendo la progressione armonica fondamentale, lo \u201cur-satz\u201d per dirla con Shenker, di tutta la musica occidentale dal tardo barocco al primo novecento e che ancora oggi vive in una certa <em>popular music<\/em>; mentre gli accordi di settima, cio\u00e8 costruiti da quattro suoni a intervalli di terza sovrapposti, devono risolvere su un accordo posto una quinta sotto o una quarta sopra.<br \/>\nA livello delle forme musicali, per esempio all&#8217;interno della <strong>forma sonata<\/strong>, si riscontra una successione di parti del processo ben strutturata: <strong>Esposizione<\/strong> = primo tema (tonalit\u00e0 di base) &#8211; ponte modulante &#8211; secondo tema (tonalit\u00e0 del V grado superiore) &#8211; ritornello; <strong>Sviluppo<\/strong> = elaborazione armonica, melodica, ritmica del materiale dell&#8217;esposizione; <strong>Ripresa<\/strong> = \u00a0primo e secondo tema nella tonalit\u00e0 di partenza. In questo senso la forma sonata \u00e8 interpretabile come <strong>processo modale<\/strong> per il quale \u201cl&#8217;auditeur est guid\u00e9 attravers\u00a0differentes zones modales sur la base de sa competence\u201d (TARASTI, 1983, pag.7)\u00a0L&#8217;elenco potrebbe continuare con una serie di regole grammaticali e formali esplicitate nei manuali di armonia o, come spesso avviene, implicite nella competenza del repertorio. Abbiamo gi\u00e0 spiegato (2.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-processo-e-sistema\/\" target=\"_blank\">Processo e sistema<\/a>) che\u00a0il punto focale cui la nostra prospettiva fa riferimento non \u00e8 il livello melodico, formale o ritmico, ma quello armonico; in particolare adottiamo\u00a0l&#8217;approccio sintagmatico-paradigmatico nell&#8217;analisi delle funzioni armoniche, facendo riferimento al concetto di <strong>sintagma funzionale<\/strong> per <em>segmentare<\/em> un brano in parti e studiarne le relazioni. (cfr.\u00a03.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-la-prova-di-commutazione\/\">Prova di commutazione<\/a>)<\/p>\n<p style=\"text-align: justify;\">Torniamo adesso alla teoria dell&#8217;informazione. Su un testo di alcuni anni fa, dedicato al rapporto tra estetica e teoria dell&#8217;informazione, ritroviamo l&#8217;intervento ormai storico di L. Meyer, musicologo che prima di altri ha tentato di spiegare il senso della musica in termini di <em>aspettiva<\/em> e <em>inferenza<\/em>. Il suo contributo ci da modo di mostrare come, quantificare l&#8217;informazione di un brano in base alla formula di Shannon e Weaver, presupponga l&#8217;analisi delle\u00a0combinazioni e delle rezioni su cui un certo testo si struttura. Meyer spiega come, se una situazione si presenta \u201cmolto organizzata e i conseguenti possibili di un dato modulo hanno un alto grado di probabilit\u00e0, l&#8217;informazione \u00e8 bassa; se invece la situazione \u00e8 caratterizzata da un alto grado di fluidit\u00e0, per cui i conseguenti sono pi\u00f9 o meno equiprobabili, l&#8217;informazione si dir\u00e0 alta\u201d (MEYER, 1957, p.161) Dal passo citato, ricordando che per informazione si intende \u201cla libert\u00e0 di scelta che si ha nel costruire un messaggio\u201d, si evince che laddove c&#8217;\u00e8 <strong>combinazione<\/strong> le aspettative sono meno forti, l&#8217;informazione molto alta e l&#8217;interesse implicato relativo; dove c&#8217;\u00e8 <strong>rezione<\/strong>\u00a0realizzata e quindi informazione bassa, l&#8217;aspettativa \u00e8 molto forte e <em>the embodied\u00a0meaning<\/em> debole; dove la rezione \u00e8 <em>non realizzata<\/em> l&#8217;informazione \u00e8 altissima e il tratto in questione altamente \u201csignificativo\u201d, cio\u00e8 interessante, stimolante, \u201cpiacevole\u201d. Abbiamo osservato che in musica non esistono casi di rezione come nei linguaggi passe-partout perch\u00e9 ogni s-codice musicale non \u00e8 mai rigoroso ma ha una sistematicit\u00e0 probabilistica; come ipotizza Ruwet, un brano musicale come pure una poesia generano in un certo senso il proprio codice del quale costituiscono l&#8217;unico messaggio. Tuttavia, come gi\u00e0 abbiamo fatto descrivendo le funzioni armoniche, \u00e8 possibile verificare come, al livello di sintagmi funzionali, <strong>il ciclo T-SD-D-T<\/strong> acquisisca\u00a0nel repertorio classico un valore strutturale cos\u00ec forte da permetterci di parlare, sia pure in senso probabilistico, di rezione. Adottando questa prospettiva &#8211; prospettiva che isola, lo ripetiamo, il parametro armonico trascurando ci\u00f2 che avviene ai livelli melodici, ritmici e formali &#8211; osserviamo che il sintagma funzionale D \u00e8 in relazione di <em>rezione unilaterale<\/em>, cio\u00e8 implica senza essere necessariamente implicato, con il sintagma T; il sintagma\u00a0SD implica il sintagma D ma meno rigidamente (basti pensare alla cadenza plagale IV-I); mentre il sintagma T \u00e8 la <em>costante<\/em> la cui presenza \u00e8 condizione necessaria per la presenza degli altri funtivi. Come si vede, la rezione <em>pi\u00f9 forte<\/em> \u00e8 quella tra i sintagmi D e T, ed \u00e8 proprio su di essa che vive il procedimento che pi\u00f9 di ogni altro arricchisce armonicamente il senso di un brano: la <strong>modulazione<\/strong> (cfr.\u00a02.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-processo-e-sistema\/\" target=\"_blank\">Processo e sistema<\/a>). Essa infatti ha sempre luogo attraverso un accordo che ha funzione di Dominante e sempre, di conseguenza, all&#8217;interno di un sintagma che \u00e8, o diventa per la sua presenza, appunto D. Senza entrare nel dettaglio analitico di singole opere, perch\u00e9 non \u00e8 questo l&#8217;obiettivo del presente lavoro, sosteniamo che sia sufficiente l&#8217;ascolto di un qualsiasi brano del repertorio classico per verificare sulla partitura che i momenti armonici pi\u00f9 stimolanti e significativi, proprio perch\u00e9 ambigui, inaspettati, impronosticabili, sono quelli in cui si verifica la modulazione.<\/p>\n<p style=\"text-align: justify;\">Un <strong>sintagma funzionale D<\/strong> che pu\u00f2 definirsi emblematico nella musica operistica e sinfonica classica, \u00e8 quello della cosiddetta \u201ccadenza di bravura\u201d: alla fine di un&#8217;aria o di un concerto, il solista, su un accordo di Dominante, aveva modo di improvvisare e mostrare tutta la sua tecnica dando vita ad un sintagma D, la cui lunghezza era discrezionale\u00a0e in cui la presenza della costante T era assolutamente immancabile. Un altro fatto che vorremmo sottolineare come particolarmente significativo in termini di rezione, \u00e8 che il sistema armonico-tonale nell&#8217;800 si amplier\u00e0 fino a logorare e superare se stesso, giocando sulla funzione D detta <em>vagante<\/em>, cio\u00e8 sospesa, di cui \u00e8 emblema la successione di accordi di settime diminuite, quinte aumentate, accordi alterati (Tristano-accordi vari), che per la loro particolare costituzione armonica\u00a0(cfr.\u00a02.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-processo-e-sistema\/\" target=\"_blank\">Processo e sistema<\/a>), possono essere interpretati come appartenenti e risolvibili in varie tonalit\u00e0 e che nella loro continua successione, non risolvendo mai, giocano, evocandola e negandola incessantemente, sulla rezione D-T.<\/p>\n<p style=\"text-align: justify;\">In alcuni repertori della <strong>popular music<\/strong> ritroviamo una struttura armonica analoga ma con alcune peculiarit\u00e0. In questi casi, infatti, il ciclo funzionale \u00e8 sempre rispettato, la struttura dell&#8217;intero brano ripetuta con regolarit\u00e0 e la modulazione pressoch\u00e9 assente, tranne talvolta nella sezione B delle canzoni a schema AABA. I due schemi di accordi fondamentali su cui, come spiega L. Faether in <em>Inside Jazz<\/em>, sono basati circa la met\u00e0 dei pezzi jazz dalle origini al Be-bop, sono la realizzazione puntuale del ciclo funzionale T-SD-D-T.<\/p>\n<p style=\"text-align: justify;\">Il <strong>giro di blues<\/strong> \u00e8 traducibile nei seguenti sintagmi funzionali:<br \/>\n<a href=\"http:\/\/www.giannicresci.com\/wp-content\/uploads\/2014\/12\/Giro-blues.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-501 size-full\" src=\"http:\/\/www.giannicresci.com\/wp-content\/uploads\/2014\/12\/Giro-blues.jpg\" alt=\"Giro di Blues - Semiotica della musica - Analisi\" width=\"400\" height=\"139\" srcset=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Giro-blues.jpg 400w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Giro-blues-300x104.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><br \/>\n<\/a>Il giro di<strong>\u00a0I Got Rhythm<\/strong> \u00e8 invece:<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-502 size-full\" src=\"http:\/\/www.giannicresci.com\/wp-content\/uploads\/2014\/12\/I-Got-Rhythm.jpg\" alt=\"I Got Rhythm - Semiotica della musica\" width=\"400\" height=\"99\" srcset=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/I-Got-Rhythm.jpg 400w, https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/I-Got-Rhythm-300x74.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">Come si vede, in questi ambiti il ciclo funzionale non \u00e8 mai evitato, disatteso, ma si ripete costantemente per tutta lunghezza del brano.<\/p>\n<p>[highlight]Tratto da Gianni Cresci e Luciano Menconi,\u00a0<em>I cinque tratti della struttura fondamentale del linguaggio secondo\u00a0Hjelmslev. La verifica nel sistema musicale attraverso una prospettiva armonico-funzionale<\/em>, Universit\u00e0 di Bologna, 1988[\/highlight]<\/p>\n<p><b><strong>1.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-espressione-e-contenuto\/\">Piano dell&#8217;espressione e piano del contenuto<\/a><\/strong><br \/>\n<strong>2.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-processo-e-sistema\/\" target=\"_blank\">Processo e sistema<\/a><\/strong><br \/>\n<strong>3.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-la-prova-di-commutazione\/\">Prova di commutazione<\/a><\/strong><br \/>\n<strong>4.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-combinazione-e-rezione\/\">Combinazione e rezione<\/a><\/strong><br \/>\n<strong>5.\u00a0<a href=\"http:\/\/www.giannicresci.com\/semiotica-della-musica-non-conformita\/\">(Non) conformit\u00e0<\/a><\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">[hr]<\/p>\n<p style=\"text-align: justify;\">HJELMSLEV, Louis<br \/>\n1968\u00a0<em>I fondamenti della teoria del linguaggio<\/em>, Torino, Einaudi<br \/>\n1985 &#8220;La struttura fondamentale del linguaggio\u201d in Versus n.43<\/p>\n<p style=\"text-align: justify;\">MEYER,\u00a0Leonard<br \/>\n1957\u00a0 \u201cSignificato in musica e teoria dell&#8217;informazione\u201d, in AA.VV Estetica e Teoria dell&#8217;informazione, Milano, Bompiani<\/p>\n<p style=\"text-align: justify;\">RUWET,\u00a0Nicolas<br \/>\n1983\u00a0Linguaggio, musica, poesia, Torino, Einaudi<\/p>\n<p style=\"text-align: justify;\">TARASTI,\u00a0Eero<br \/>\n1983\u00a0\u00a0\u201cSur les structures elementaires du discors musical\u201d, Actes semiotiques,\u00a0VI\/dec.<\/p>\n<p style=\"text-align: justify;\"><span class=\"Apple-style-span\">ZINNA, Alessandro<br \/>\n1985 Introduzione in\u00a0<em>Versus<\/em>\u00a0n.43<\/span><\/p>\n<p style=\"text-align: justify;\">[hr]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Combinazione e Rezione Il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[11,15,50,60,70,79,89,93],"class_list":["post-476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testi","tag-analisi-musicale","tag-armonia","tag-hjelmslev","tag-jazz","tag-musicologia","tag-popular-music","tag-semiotica","tag-semiotica-della-musica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semiotica della musica. Combinazione e rezione - Gianni Cresci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semiotica della musica. Combinazione e rezione - Gianni Cresci\" \/>\n<meta property=\"og:description\" content=\"Combinazione e Rezione Il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/\" \/>\n<meta property=\"og:site_name\" content=\"Gianni Cresci\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-08T17:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Giro-blues.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"headline\":\"Semiotica della musica. Combinazione e rezione\",\"datePublished\":\"2014-12-08T17:29:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/\"},\"wordCount\":1611,\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Semiotica-della-musica-combinazione-rezione.jpg\",\"keywords\":[\"Analisi musicale\",\"Armonia\",\"Hjelmslev\",\"Jazz\",\"Musicologia\",\"Popular Music\",\"Semiotica\",\"Semiotica della musica\"],\"articleSection\":[\"Testi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/\",\"name\":\"Semiotica della musica. Combinazione e rezione - Gianni Cresci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Semiotica-della-musica-combinazione-rezione.jpg\",\"datePublished\":\"2014-12-08T17:29:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Semiotica-della-musica-combinazione-rezione.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Semiotica-della-musica-combinazione-rezione.jpg\",\"width\":302,\"height\":252,\"caption\":\"Combinazione e rezione. Semiotica della musica, i tratti fondamentali del linguaggio musicale.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/2014\\\/12\\\/08\\\/semiotica-della-musica-combinazione-e-rezione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semiotica della musica. Combinazione e rezione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#website\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/\",\"name\":\"Gianni Cresci\",\"description\":\"Semiotica, Musica, Design e Comunicazione.\",\"publisher\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/#\\\/schema\\\/person\\\/54f27d952ab7ef46ffa9b1afa752a811\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"contentUrl\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\",\"width\":512,\"height\":512,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cropped-Gianni-Cresci-FB1.jpg\"},\"sameAs\":[\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\"],\"url\":\"https:\\\/\\\/giannicresci.com\\\/Gianni-Cresci\\\/index.php\\\/author\\\/admin_gianni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semiotica della musica. Combinazione e rezione - Gianni Cresci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/","og_locale":"it_IT","og_type":"article","og_title":"Semiotica della musica. Combinazione e rezione - Gianni Cresci","og_description":"Combinazione e Rezione Il [&hellip;]","og_url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/","og_site_name":"Gianni Cresci","article_published_time":"2014-12-08T17:29:16+00:00","og_image":[{"width":400,"height":139,"url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Giro-blues.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#article","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/"},"author":{"name":"admin","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"headline":"Semiotica della musica. Combinazione e rezione","datePublished":"2014-12-08T17:29:16+00:00","mainEntityOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/"},"wordCount":1611,"publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Semiotica-della-musica-combinazione-rezione.jpg","keywords":["Analisi musicale","Armonia","Hjelmslev","Jazz","Musicologia","Popular Music","Semiotica","Semiotica della musica"],"articleSection":["Testi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/","name":"Semiotica della musica. Combinazione e rezione - Gianni Cresci","isPartOf":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#primaryimage"},"image":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#primaryimage"},"thumbnailUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Semiotica-della-musica-combinazione-rezione.jpg","datePublished":"2014-12-08T17:29:16+00:00","breadcrumb":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#primaryimage","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Semiotica-della-musica-combinazione-rezione.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/12\/Semiotica-della-musica-combinazione-rezione.jpg","width":302,"height":252,"caption":"Combinazione e rezione. Semiotica della musica, i tratti fondamentali del linguaggio musicale."},{"@type":"BreadcrumbList","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/2014\/12\/08\/semiotica-della-musica-combinazione-e-rezione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giannicresci.com\/Gianni-Cresci\/"},{"@type":"ListItem","position":2,"name":"Semiotica della musica. Combinazione e rezione"}]},{"@type":"WebSite","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#website","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/","name":"Gianni Cresci","description":"Semiotica, Musica, Design e Comunicazione.","publisher":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giannicresci.com\/Gianni-Cresci\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/#\/schema\/person\/54f27d952ab7ef46ffa9b1afa752a811","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","url":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","contentUrl":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg","width":512,"height":512,"caption":"admin"},"logo":{"@id":"https:\/\/giannicresci.com\/Gianni-Cresci\/wp-content\/uploads\/2014\/11\/cropped-Gianni-Cresci-FB1.jpg"},"sameAs":["https:\/\/giannicresci.com\/Gianni-Cresci"],"url":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/author\/admin_gianni\/"}]}},"_links":{"self":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media\/504"}],"wp:attachment":[{"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giannicresci.com\/Gianni-Cresci\/index.php\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}